{"id":13150,"date":"2020-02-12T08:51:30","date_gmt":"2020-02-12T07:51:30","guid":{"rendered":"https:\/\/kongernesferiepark.dk\/devant\/"},"modified":"2026-01-05T09:11:08","modified_gmt":"2026-01-05T08:11:08","slug":"devant","status":"publish","type":"page","link":"https:\/\/kongernesferiepark.dk\/fr\/","title":{"rendered":"Devant"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13150\" class=\"elementor elementor-13150 elementor-15\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49fd45f1 white e-flex e-con-boxed e-con e-parent\" data-id=\"49fd45f1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/gostmediaserviceprod.blob.core.windows.net\\\/asset-8924ae05-b924-4a42-90b5-4a0baa05dd52\\\/hero_1920x1080_6000k.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500.2,94.7L0,0v100h1000V0L500.2,94.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cb92e44 e-con-full e-flex e-con e-child\" data-id=\"1cb92e44\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-758808e3 prehead elementor-widget elementor-widget-text-editor\" data-id=\"758808e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bienvenue sur  Kongernes Feriepark<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f613852 elementor-widget elementor-widget-heading\" data-id=\"f613852\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Camping dans un cadre pittoresque  <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3857817b e-con-full e-flex e-con e-child\" data-id=\"3857817b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f7781ba cta elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"2f7781ba\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/booking.octopuspms.com\/RoomBook?code=ed1f8642-6587-41f0-8273-1f69f73c1e23\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servation en ligne<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fddc5c0 elementor-mobile-align-justify elementor-widget-mobile__width-inherit tonedwhite elementor-widget elementor-widget-button\" data-id=\"2fddc5c0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kongernesferiepark.dk\/fr\/prix\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consultez nos prix<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8035e7b e-flex e-con-boxed e-con e-parent\" data-id=\"8035e7b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec4d1f5 elementor-widget elementor-widget-text-editor\" data-id=\"ec4d1f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Des vacances inoubliables avec une grande piscine et un cadre chaleureux<\/h2><p>Vous r\u00eavez de vacances ou d&rsquo;un s\u00e9jour o\u00f9 il y a place pour la d\u00e9tente, la convivialit\u00e9 et une multitude d&rsquo;exp\u00e9riences ?<br> Au <a href=\"\/\">Kongernes Feriepark,<\/a> vous trouverez un camping moderne au c\u0153ur de la magnifique r\u00e9gion du nord de la Z\u00e9lande. Nous sommes situ\u00e9s \u00e0 Smidstrup Strand, pr\u00e8s de Gilleleje et \u00e0 seulement une heure de route de Copenhague. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d25bd5 elementor-widget__width-initial elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"0d25bd5\" data-element_type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;curly&quot;,&quot;highlighted_text&quot;:&quot;Ici, vous pouvez d\\u00e9connecter, profiter de la nature tout en restant proche de la plage, de la for\\u00eat et d&#039;une multitude d&#039;activit\\u00e9s.&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_animation_duration&quot;:1200,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Ici, vous pouvez d\u00e9connecter, profiter de la nature tout en restant proche de la plage, de la for\u00eat et d'une multitude d'activit\u00e9s.<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5572ec0c e-con-full no-padding e-flex e-con e-parent\" data-id=\"5572ec0c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-54aa73a6 e-con-full no-padding e-flex e-con e-child\" data-id=\"54aa73a6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58a6f5be elementor-cta--skin-cover elementor-widget__width-inherit elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"58a6f5be\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/kongernesferiepark.dk\/overnatning\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/H6-203-koekken.jpg);\" role=\"img\" aria-label=\"Tr\u00e6hytte til overnatning i Gr\u00e6sted ved Gilleleje\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/krone.svg\" class=\"attachment-full size-full wp-image-12297\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tH\u00e9bergement\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tEn savoir plus\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5def41be e-con-full no-padding e-flex e-con e-child\" data-id=\"5def41be\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55e2859b elementor-cta--skin-cover elementor-widget__width-inherit elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"55e2859b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/kongernesferiepark.dk\/oplevelser\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/Oversigt-4.jpg);\" role=\"img\" aria-label=\"Campingplads med overnatning og pool i Gr\u00e6sted\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/krone.svg\" class=\"attachment-full size-full wp-image-12297\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tActivit\u00e9s\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tEn savoir plus\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87b7d65 e-con-full no-padding e-flex e-con e-child\" data-id=\"87b7d65\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-272d50ca elementor-cta--skin-cover elementor-widget__width-inherit elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"272d50ca\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/kongernesferiepark.dk\/priser\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/Amalienborg-aften-3-1600.jpg);\" role=\"img\" aria-label=\"Amalienborg-aften-3-1600\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"80\" height=\"80\" src=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/krone.svg\" class=\"attachment-full size-full wp-image-12297\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPrix\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tEn savoir plus\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e48a255 e-flex e-con-boxed e-con e-parent\" data-id=\"2e48a255\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3542d2cb e-con-full e-flex e-con e-child\" data-id=\"3542d2cb\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fcf617e e-con-full e-flex e-con e-child\" data-id=\"fcf617e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec939d9 elementor-widget elementor-widget-text-editor\" data-id=\"ec939d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>H\u00e9bergement pour tous les besoins<\/h2><p>Chez nous, l&rsquo;important est de trouver l&rsquo;h\u00e9bergement qui vous convient, \u00e0 vous et \u00e0 vos proches. Si vous pr\u00e9f\u00e9rez le camping traditionnel en tente, caravane ou camping-car, vous trouverez de vastes espaces verts. Pour plus de confort, optez pour un chalet douillet avec terrasse, id\u00e9al pour les familles comme pour les couples. Nous proposons \u00e9galement des chambres avec salle de bain et toilettes privatives, ainsi que des appartements au bord de la piscine, pour un confort optimal.   <\/p><p>Cela signifie que nous pouvons accueillir aussi bien des particuliers souhaitant partir en vacances en famille ou en week-end, que des entreprises recherchant un cadre pour un \u00e9v\u00e9nement informel avec h\u00e9bergement sur place.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-255dfd3 cta elementor-widget elementor-widget-button\" data-id=\"255dfd3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kongernesferiepark.dk\/fr\/contactez-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous d\u00e8s aujourd'hui<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1506e8cf e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1506e8cf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10f52eb4 e-flex e-con-boxed e-con e-parent\" data-id=\"10f52eb4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56d19154 e-con-full e-flex e-con e-child\" data-id=\"56d19154\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-25e2e8d1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"25e2e8d1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c6f4bb9 e-con-full e-flex e-con e-child\" data-id=\"5c6f4bb9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba8f10 elementor-widget elementor-widget-text-editor\" data-id=\"2ba8f10\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>De nombreuses activit\u00e9s et exp\u00e9riences partag\u00e9es<\/h2><p>Ce qui est formidable avec notre camping, c&rsquo;est qu&rsquo;il y a toujours de l&rsquo;animation, si vous le souhaitez. Nous avons une grande piscine ext\u00e9rieure, un mini-golf, un terrain multisports et une aire de jeux amusante pour les enfants. Tout est regroup\u00e9 pour que famille ou coll\u00e8gues puissent s&rsquo;amuser ensemble.  <\/p><p>Nous disposons \u00e9galement d&rsquo;une salle de r\u00e9ception chaleureuse, id\u00e9ale pour tous vos \u00e9v\u00e9nements, des anniversaires et confirmations aux \u00e9v\u00e9nements d&rsquo;entreprise ou r\u00e9unions d&rsquo;association. Et si vous avez un petit creux, n&rsquo;h\u00e9sitez pas \u00e0 faire une halte au Restaurant G\u00e5rdhaven, o\u00f9 nous proposons une cuisine maison et organisons des \u00e9v\u00e9nements tout au long de l&rsquo;ann\u00e9e, comme des banquets ou des soir\u00e9es \u00e0 th\u00e8me. <\/p><p>En r\u00e9sum\u00e9&nbsp;: il y a des activit\u00e9s pour les enfants comme pour les adultes, et de l\u2019espace pour se r\u00e9unir, que vous veniez en famille, entre amis ou en \u00e9quipe de coll\u00e8gues.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d219ca cta e-transform elementor-widget elementor-widget-button\" data-id=\"3d219ca\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kongernesferiepark.dk\/fr\/contactez-nous\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous d\u00e8s aujourd'hui<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38d2249b e-con-full no-padding accent e-flex e-con e-parent\" data-id=\"38d2249b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5375a367 e-con-full e-flex e-con e-child\" data-id=\"5375a367\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d48245f e-con-full contained left e-flex elementor-invisible e-con e-child\" data-id=\"2d48245f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d767d47 elementor-widget elementor-widget-text-editor\" data-id=\"5d767d47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Combien co\u00fbte le camping ?<\/h2><p>Le prix du camping d\u00e9pend du type d&rsquo;h\u00e9bergement choisi&nbsp;: emplacement pour tente ou caravane, chalet, chambre ou appartement pr\u00e8s de la piscine et du jacuzzi. Nous proposons diff\u00e9rents tarifs pour tous les budgets. Consultez notre page \u00ab&nbsp;Tarifs&nbsp;\u00bb pour d\u00e9couvrir nos offres et les prix du moment. Nous la mettons \u00e0 jour r\u00e9guli\u00e8rement pour vous permettre d&rsquo;avoir une vue d&rsquo;ensemble facile.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c470a44 border elementor-widget elementor-widget-button\" data-id=\"2c470a44\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kongernesferiepark.dk\/fr\/prix\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Consultez nos prix<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23883be light e-flex e-con-boxed e-con e-parent\" data-id=\"23883be\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-42bf9df e-con-full e-flex e-con e-child\" data-id=\"42bf9df\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-21d1028 e-con-full e-flex e-con e-child\" data-id=\"21d1028\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0b1c2a elementor-widget elementor-widget-google_maps\" data-id=\"d0b1c2a\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Helsingevej%2044%2C%203230%20Gr%C3%A6sted&#038;t=m&#038;z=12&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Helsingevej 44, 3230 Gr\u00e6sted\"\n\t\t\t\t\taria-label=\"Helsingevej 44, 3230 Gr\u00e6sted\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-add8139 e-con-full e-flex e-con e-child\" data-id=\"add8139\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e184f0d elementor-widget elementor-widget-text-editor\" data-id=\"e184f0d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Un camping bien situ\u00e9<\/h2><p>Nous sommes particuli\u00e8rement fiers de notre emplacement. Notre camping se situe au c\u0153ur de la nature verdoyante du nord de la Z\u00e9lande \u2013 un havre de calme et de tranquillit\u00e9 \u2013 tout en \u00e9tant proche de nombreuses activit\u00e9s. <\/p><p>Vous pouvez faire une excursion en Louisiane, visiter le charmant port de Gilleleje ou faire un tour au mus\u00e9e maritime M\/S. Et par beau temps, la plage est \u00e0 quelques minutes seulement&nbsp;: vous pourrez vous baigner ou simplement vous pr\u00e9lasser au soleil. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd9ad5e cta e-transform elementor-widget elementor-widget-button\" data-id=\"bd9ad5e\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/booking.octopuspms.com\/RoomBook?code=ed1f8642-6587-41f0-8273-1f69f73c1e23\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servez en ligne<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c5d396 e-flex e-con-boxed e-con e-parent\" data-id=\"3c5d396\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56ea0a5 e-con-full e-flex e-con e-child\" data-id=\"56ea0a5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5784231 elementor-widget elementor-widget-heading\" data-id=\"5784231\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos partenaires<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df41e71 elementor-widget elementor-widget-gallery\" data-id=\"df41e71\" data-element_type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:4,&quot;columns_mobile&quot;:2,&quot;image_hover_animation&quot;:&quot;grow&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/1.png\" data-width=\"1500\" data-height=\"1500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/2-1.png\" data-width=\"1500\" data-height=\"1500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/3.png\" data-width=\"1500\" data-height=\"1500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"e-gallery-item elementor-gallery-item elementor-animated-content\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/4.png\" data-width=\"1500\" data-height=\"1500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c8d9ea e-con-full e-flex e-con e-parent\" data-id=\"1c8d9ea\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3386d0 elementor-widget elementor-widget-template\" data-id=\"a3386d0\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"13513\" class=\"elementor elementor-13513 elementor-10411\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b01ab3c white e-con-full e-flex e-con e-parent\" data-id=\"b01ab3c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t<div class=\"elementor-element elementor-element-40b4ae8f e-con-full e-flex e-con e-child\" data-id=\"40b4ae8f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-100a64e elementor-widget elementor-widget-image\" data-id=\"100a64e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"123\" height=\"206\" src=\"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/logo-icon.svg\" class=\"attachment-full size-full wp-image-11548\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a35733e elementor-widget elementor-widget-text-editor\" data-id=\"4a35733e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>R\u00e9servez vos vacances ou votre \u00e9v\u00e9nement avec nous<\/h2><p>Envie de vacances chaleureuses et riches en exp\u00e9riences inoubliables&nbsp;? Ou bien d\u2019un lieu pour r\u00e9unir famille, amis ou coll\u00e8gues&nbsp;? Kongernes Feriepark est la solution id\u00e9ale. Nous serons ravis de vous accueillir et de cr\u00e9er le cadre parfait pour tous vos \u00e9v\u00e9nements, d\u2019un week-end tranquille \u00e0 une sortie d\u2019entreprise r\u00e9ussie.  <\/p><p>Contactez-nous d\u00e8s aujourd&rsquo;hui pour r\u00e9server ou obtenir plus d&rsquo;informations. Vous pouvez nous appeler au<a href=\"tel:48318448\" aria-label=\"Telefon nummer\">48 31 84 48<\/a> ou \u00e9crivez-nous \u00e0   <a href=\"mailto:info@kongernesferiepark.dk\" aria-label=\"Email adresse\">info@kongernesferiepark.dk<\/a><\/p><p>\u00c0 bient\u00f4t au camping ! \u2013 Vos h\u00f4tes, la famille Lundsh\u00f8j.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bienvenue sur Camping dans un cadre pittoresque R\u00e9servation en ligne Consultez nos prix Des vacances inoubliables avec une grande piscine et un cadre chaleureux Vous r\u00eavez de vacances ou d&rsquo;un s\u00e9jour o\u00f9 il y a place pour la d\u00e9tente, la convivialit\u00e9 et une multitude d&rsquo;exp\u00e9riences ? Au Kongernes Feriepark, vous trouverez un camping moderne au &#8230; <a title=\"Devant\" class=\"read-more\" href=\"https:\/\/kongernesferiepark.dk\/fr\/\" aria-label=\"En savoir plus sur Devant\">Lire plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"class_list":["post-13150","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord<\/title>\n<meta name=\"description\" content=\"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kongernesferiepark.dk\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord\" \/>\n<meta property=\"og:description\" content=\"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kongernesferiepark.dk\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Kongernes Feriepark\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T08:11:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/\",\"url\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/\",\"name\":\"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kongernesferiepark.dk\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/krone.svg\",\"datePublished\":\"2020-02-12T07:51:30+00:00\",\"dateModified\":\"2026-01-05T08:11:08+00:00\",\"description\":\"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kongernesferiepark.dk\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/krone.svg\",\"contentUrl\":\"https:\\\/\\\/kongernesferiepark.dk\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/krone.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Forside\",\"item\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Devant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/\",\"name\":\"Kongernes Feriepark\",\"description\":\"Campingplads i natursk\u00f8nne omgivelser\",\"publisher\":{\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#organization\",\"name\":\"Kongernes Feriepark\",\"url\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kongernesferiepark.dk\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/kongernesferiepark.dk\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.svg\",\"width\":614,\"height\":206,\"caption\":\"Kongernes Feriepark\"},\"image\":{\"@id\":\"https:\\\/\\\/kongernesferiepark.dk\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord","description":"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kongernesferiepark.dk\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord","og_description":"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord","og_url":"https:\/\/kongernesferiepark.dk\/fr\/","og_site_name":"Kongernes Feriepark","article_modified_time":"2026-01-05T08:11:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kongernesferiepark.dk\/fr\/","url":"https:\/\/kongernesferiepark.dk\/fr\/","name":"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord","isPartOf":{"@id":"https:\/\/kongernesferiepark.dk\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kongernesferiepark.dk\/fr\/#primaryimage"},"image":{"@id":"https:\/\/kongernesferiepark.dk\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/krone.svg","datePublished":"2020-02-12T07:51:30+00:00","dateModified":"2026-01-05T08:11:08+00:00","description":"Kongernes Feriepark | Vacances dans la belle Z\u00e9lande du Nord","breadcrumb":{"@id":"https:\/\/kongernesferiepark.dk\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kongernesferiepark.dk\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kongernesferiepark.dk\/fr\/#primaryimage","url":"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/krone.svg","contentUrl":"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/krone.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/kongernesferiepark.dk\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Forside","item":"https:\/\/kongernesferiepark.dk\/fr\/"},{"@type":"ListItem","position":2,"name":"Devant"}]},{"@type":"WebSite","@id":"https:\/\/kongernesferiepark.dk\/fr\/#website","url":"https:\/\/kongernesferiepark.dk\/fr\/","name":"Kongernes Feriepark","description":"Campingplads i natursk\u00f8nne omgivelser","publisher":{"@id":"https:\/\/kongernesferiepark.dk\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kongernesferiepark.dk\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kongernesferiepark.dk\/fr\/#organization","name":"Kongernes Feriepark","url":"https:\/\/kongernesferiepark.dk\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kongernesferiepark.dk\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/logo.svg","contentUrl":"https:\/\/kongernesferiepark.dk\/wp-content\/uploads\/2025\/10\/logo.svg","width":614,"height":206,"caption":"Kongernes Feriepark"},"image":{"@id":"https:\/\/kongernesferiepark.dk\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/pages\/13150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/comments?post=13150"}],"version-history":[{"count":2,"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/pages\/13150\/revisions"}],"predecessor-version":[{"id":14391,"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/pages\/13150\/revisions\/14391"}],"wp:attachment":[{"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/media?parent=13150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kongernesferiepark.dk\/fr\/wp-json\/wp\/v2\/categories?post=13150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}